{"id":8364,"date":"2023-03-26T09:44:51","date_gmt":"2023-03-26T07:44:51","guid":{"rendered":"https:\/\/catholiques17.fr\/nieul\/?post_type=tribe_events&#038;p=8364"},"modified":"2023-03-26T09:44:51","modified_gmt":"2023-03-26T07:44:51","slug":"preparation-liturgies-de-la-semaine-sainte","status":"publish","type":"tribe_events","link":"https:\/\/catholiques17.fr\/nieul\/event\/preparation-liturgies-de-la-semaine-sainte\/","title":{"rendered":"Pr\u00e9paration liturgies de la semaine sainte"},"content":{"rendered":"<p>Afin de pr\u00e9parer les diff\u00e9rentes c\u00e9l\u00e9brations de la semaine sainte et de P\u00e2ques, vous \u00eates tous invit\u00e9s \u00e0 venir nous rejoindre le jeudi 30 mars \u00e0 18h, salle Gabriel Coll (presbyt\u00e8re de Nieul)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afin de pr\u00e9parer les diff\u00e9rentes c\u00e9l\u00e9brations de la semaine sainte et de P\u00e2ques, vous \u00eates tous invit\u00e9s \u00e0 venir nous rejoindre le jeudi 30 mars \u00e0 18h, salle Gabriel Coll [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7021,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-8364","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events\/8364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events\/8364\/revisions"}],"predecessor-version":[{"id":8365,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events\/8364\/revisions\/8365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/media\/7021"}],"wp:attachment":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/media?parent=8364"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tags?post=8364"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events_cat?post=8364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}