{"id":8217,"date":"2023-02-23T08:33:55","date_gmt":"2023-02-23T07:33:55","guid":{"rendered":"https:\/\/catholiques17.fr\/nieul\/?post_type=tribe_events&#038;p=8217"},"modified":"2023-02-23T08:34:23","modified_gmt":"2023-02-23T07:34:23","slug":"messe-chrismale-2","status":"publish","type":"tribe_events","link":"https:\/\/catholiques17.fr\/nieul\/event\/messe-chrismale-2\/","title":{"rendered":"Messe chrismale"},"content":{"rendered":"<p>Le lundi 3 avril, lundi saint, la messe chrismale sera c\u00e9l\u00e9br\u00e9e \u00e0 18h \u00e0 la cath\u00e9drale St Louis \u00e0 La Rochelle.<\/p>\n<p>Au cours de cette c\u00e9l\u00e9bration, l\u2019\u00e9v\u00eaque b\u00e9nira les huiles saintes et consacrera le Saint Chr\u00eame. Les pr\u00eatres renouvelleront leurs promesses sacerdotales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le lundi 3 avril, lundi saint, la messe chrismale sera c\u00e9l\u00e9br\u00e9e \u00e0 18h \u00e0 la cath\u00e9drale St Louis \u00e0 La Rochelle. Au cours de cette c\u00e9l\u00e9bration, l\u2019\u00e9v\u00eaque b\u00e9nira les huiles [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8218,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-8217","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events\/8217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events\/8217\/revisions"}],"predecessor-version":[{"id":8219,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events\/8217\/revisions\/8219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/media\/8218"}],"wp:attachment":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/media?parent=8217"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tags?post=8217"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events_cat?post=8217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}