{"id":8191,"date":"2023-02-13T09:50:42","date_gmt":"2023-02-13T08:50:42","guid":{"rendered":"https:\/\/catholiques17.fr\/nieul\/?post_type=tribe_events&#038;p=8191"},"modified":"2023-02-13T09:50:42","modified_gmt":"2023-02-13T08:50:42","slug":"mercredi-des-cendres","status":"publish","type":"tribe_events","link":"https:\/\/catholiques17.fr\/nieul\/event\/mercredi-des-cendres\/","title":{"rendered":"Mercredi des Cendres"},"content":{"rendered":"<div class=\"vc_empty_space\"><\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"spotlight01\">\n<p>Le Mercredi des cendres, premier jour du Car\u00eame, est marqu\u00e9 par l\u2019imposition des cendres : le pr\u00eatre d\u00e9pose un peu de cendres sur le front de chaque fid\u00e8le, en signe de la fragilit\u00e9 de l\u2019homme, mais aussi de l\u2019esp\u00e9rance en la mis\u00e9ricorde de Dieu. En 20223 il est f\u00eat\u00e9 le mercredi 22 f\u00e9vrier.<\/p>\n<p>La messe des Cendres sera c\u00e9l\u00e9br\u00e9e \u00e0 l&rsquo;\u00e9glise de Nieul, \u00e0 18h.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Mercredi des cendres, premier jour du Car\u00eame, est marqu\u00e9 par l\u2019imposition des cendres : le pr\u00eatre d\u00e9pose un peu de cendres sur le front de chaque fid\u00e8le, en signe [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8192,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-8191","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events\/8191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events\/8191\/revisions"}],"predecessor-version":[{"id":8193,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events\/8191\/revisions\/8193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/media\/8192"}],"wp:attachment":[{"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/media?parent=8191"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tags?post=8191"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/catholiques17.fr\/nieul\/wp-json\/wp\/v2\/tribe_events_cat?post=8191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}